{"id":17549,"date":"2020-06-12T10:38:19","date_gmt":"2020-06-12T08:38:19","guid":{"rendered":"http:\/\/www.dexway.com\/?p=17549"},"modified":"2024-07-29T12:40:20","modified_gmt":"2024-07-29T10:40:20","slug":"tecnologia-educativa-forma-mas-avanzada-ensenar-idiomas","status":"publish","type":"post","link":"https:\/\/www.dexway.com\/es\/tecnologia-educativa-forma-mas-avanzada-ensenar-idiomas\/","title":{"rendered":"Tecnolog\u00eda educativa: la forma m\u00e1s avanzada de ense\u00f1ar idiomas"},"content":{"rendered":"<span class=\"synved-social-container synved-social-container-share\"><a class=\"synved-social-button synved-social-button-share synved-social-size-32 synved-social-resolution-single synved-social-provider-facebook nolightbox\" data-provider=\"facebook\" target=\"_blank\" rel=\"nofollow\" title=\"Share on Facebook\" href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Fwww.dexway.com%2Fes%2Fwp-json%2Fwp%2Fv2%2Fposts%2F17549%2F&amp;t=Tecnolog%C3%ADa%20educativa%3A%20la%20forma%20m%C3%A1s%20avanzada%20de%20ense%C3%B1ar%20idiomas&amp;s=100&amp;p[url]=https%3A%2F%2Fwww.dexway.com%2Fes%2Fwp-json%2Fwp%2Fv2%2Fposts%2F17549%2F&amp;p[images][0]=https%3A%2F%2Fwww.dexway.com%2Fwp-content%2Fuploads%2F2016%2F01%2Feducational-technology.jpg&amp;p[title]=Tecnolog%C3%ADa%20educativa%3A%20la%20forma%20m%C3%A1s%20avanzada%20de%20ense%C3%B1ar%20idiomas\" style=\"font-size: 0px;width:32px;height:32px;margin:0;margin-bottom:5px;margin-right:5px\"><img loading=\"lazy\" decoding=\"async\" alt=\"Facebook\" title=\"Share on Facebook\" class=\"synved-share-image synved-social-image synved-social-image-share\" width=\"32\" height=\"32\" style=\"display: inline;width:32px;height:32px;margin: 0;padding: 0;border: none;box-shadow: none\" src=\"https:\/\/www.dexway.com\/wp-content\/plugins\/social-media-feather\/synved-social\/addons\/extra-icons\/image\/social\/clearslate\/64x64\/facebook.png\" \/><\/a><a class=\"synved-social-button synved-social-button-share synved-social-size-32 synved-social-resolution-single synved-social-provider-twitter nolightbox\" data-provider=\"twitter\" target=\"_blank\" rel=\"nofollow\" title=\"Share on Twitter\" href=\"https:\/\/twitter.com\/intent\/tweet?url=https%3A%2F%2Fwww.dexway.com%2Fes%2Fwp-json%2Fwp%2Fv2%2Fposts%2F17549%2F&amp;text=Hey%20check%20this%20out\" style=\"font-size: 0px;width:32px;height:32px;margin:0;margin-bottom:5px;margin-right:5px\"><img loading=\"lazy\" decoding=\"async\" alt=\"twitter\" title=\"Share on Twitter\" class=\"synved-share-image synved-social-image synved-social-image-share\" width=\"32\" height=\"32\" style=\"display: inline;width:32px;height:32px;margin: 0;padding: 0;border: none;box-shadow: none\" src=\"https:\/\/www.dexway.com\/wp-content\/plugins\/social-media-feather\/synved-social\/addons\/extra-icons\/image\/social\/clearslate\/64x64\/twitter.png\" \/><\/a><a class=\"synved-social-button synved-social-button-share synved-social-size-32 synved-social-resolution-single synved-social-provider-reddit nolightbox\" data-provider=\"reddit\" target=\"_blank\" rel=\"nofollow\" title=\"Share on Reddit\" href=\"https:\/\/www.reddit.com\/submit?url=https%3A%2F%2Fwww.dexway.com%2Fes%2Fwp-json%2Fwp%2Fv2%2Fposts%2F17549%2F&amp;title=Tecnolog%C3%ADa%20educativa%3A%20la%20forma%20m%C3%A1s%20avanzada%20de%20ense%C3%B1ar%20idiomas\" style=\"font-size: 0px;width:32px;height:32px;margin:0;margin-bottom:5px;margin-right:5px\"><img loading=\"lazy\" decoding=\"async\" alt=\"reddit\" title=\"Share on Reddit\" class=\"synved-share-image synved-social-image synved-social-image-share\" width=\"32\" height=\"32\" style=\"display: inline;width:32px;height:32px;margin: 0;padding: 0;border: none;box-shadow: none\" src=\"https:\/\/www.dexway.com\/wp-content\/plugins\/social-media-feather\/synved-social\/addons\/extra-icons\/image\/social\/clearslate\/64x64\/reddit.png\" \/><\/a><a class=\"synved-social-button synved-social-button-share synved-social-size-32 synved-social-resolution-single synved-social-provider-pinterest nolightbox\" data-provider=\"pinterest\" target=\"_blank\" rel=\"nofollow\" title=\"Pin it with Pinterest\" href=\"https:\/\/pinterest.com\/pin\/create\/button\/?url=https%3A%2F%2Fwww.dexway.com%2Fes%2Fwp-json%2Fwp%2Fv2%2Fposts%2F17549%2F&amp;media=https%3A%2F%2Fwww.dexway.com%2Fwp-content%2Fuploads%2F2016%2F01%2Feducational-technology.jpg&amp;description=Tecnolog%C3%ADa%20educativa%3A%20la%20forma%20m%C3%A1s%20avanzada%20de%20ense%C3%B1ar%20idiomas\" style=\"font-size: 0px;width:32px;height:32px;margin:0;margin-bottom:5px;margin-right:5px\"><img loading=\"lazy\" decoding=\"async\" alt=\"pinterest\" title=\"Pin it with Pinterest\" class=\"synved-share-image synved-social-image synved-social-image-share\" width=\"32\" height=\"32\" style=\"display: inline;width:32px;height:32px;margin: 0;padding: 0;border: none;box-shadow: none\" src=\"https:\/\/www.dexway.com\/wp-content\/plugins\/social-media-feather\/synved-social\/addons\/extra-icons\/image\/social\/clearslate\/64x64\/pinterest.png\" \/><\/a><a class=\"synved-social-button synved-social-button-share synved-social-size-32 synved-social-resolution-single synved-social-provider-linkedin nolightbox\" data-provider=\"linkedin\" target=\"_blank\" rel=\"nofollow\" title=\"Share on Linkedin\" href=\"https:\/\/www.linkedin.com\/shareArticle?mini=true&amp;url=https%3A%2F%2Fwww.dexway.com%2Fes%2Fwp-json%2Fwp%2Fv2%2Fposts%2F17549%2F&amp;title=Tecnolog%C3%ADa%20educativa%3A%20la%20forma%20m%C3%A1s%20avanzada%20de%20ense%C3%B1ar%20idiomas\" style=\"font-size: 0px;width:32px;height:32px;margin:0;margin-bottom:5px;margin-right:5px\"><img loading=\"lazy\" decoding=\"async\" alt=\"linkedin\" title=\"Share on Linkedin\" class=\"synved-share-image synved-social-image synved-social-image-share\" width=\"32\" height=\"32\" style=\"display: inline;width:32px;height:32px;margin: 0;padding: 0;border: none;box-shadow: none\" src=\"https:\/\/www.dexway.com\/wp-content\/plugins\/social-media-feather\/synved-social\/addons\/extra-icons\/image\/social\/clearslate\/64x64\/linkedin.png\" \/><\/a><a class=\"synved-social-button synved-social-button-share synved-social-size-32 synved-social-resolution-single synved-social-provider-mail nolightbox\" data-provider=\"mail\" rel=\"nofollow\" title=\"Share by email\" href=\"mailto:?subject=Tecnolog%C3%ADa%20educativa%3A%20la%20forma%20m%C3%A1s%20avanzada%20de%20ense%C3%B1ar%20idiomas&amp;body=Hey%20check%20this%20out:%20https%3A%2F%2Fwww.dexway.com%2Fes%2Fwp-json%2Fwp%2Fv2%2Fposts%2F17549%2F\" style=\"font-size: 0px;width:32px;height:32px;margin:0;margin-bottom:5px\"><img loading=\"lazy\" decoding=\"async\" alt=\"mail\" title=\"Share by email\" class=\"synved-share-image synved-social-image synved-social-image-share\" width=\"32\" height=\"32\" style=\"display: inline;width:32px;height:32px;margin: 0;padding: 0;border: none;box-shadow: none\" src=\"https:\/\/www.dexway.com\/wp-content\/plugins\/social-media-feather\/synved-social\/addons\/extra-icons\/image\/social\/clearslate\/64x64\/mail.png\" \/><\/a><\/span><p>La <strong>ense\u00f1anza de idiomas<\/strong> en academias y unidades de idiomas de universidades ha sido tradicionalmente un sector reacio a adoptar <strong>tecnolog\u00eda educativa<\/strong>: hasta el momento, era un sector por debajo de la media en transformaci\u00f3n digital. Las causas que lo explican las se\u00f1alamos ampliamente en <a href=\"https:\/\/www.cae.net\/es\/libro-blanco-los-centros-de-idiomas-nueva-tecnologia\/\">nuestro libro blanco<\/a> sobre academias de idiomas y las nuevas tecnolog\u00edas. \u00a0Sin embargo, ha cambiado el panorama internacional, y hemos asistido a una aceleraci\u00f3n en el proceso de transformaci\u00f3n que sit\u00faa al sector a\u00f1os por delante, en tan solo pocas semanas. La\u00a0 necesidad de dar continuidad a sus formaciones y tenerlo que hacer de forma remota ha incorporado herramientas digitales en academias de idiomas y universidades que hasta el momento solo ofrec\u00edan la posibilidad de un aprendizaje en el aula, o como mucho, con un acceso a un repositorio online.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-5033\" src=\"http:\/\/www.dexway.com\/wp-content\/uploads\/2016\/01\/educational-technology.jpg\" alt=\"Tecnolog\u00eda educativa: un futuro que ya ha llegado\" width=\"824\" height=\"460\" srcset=\"https:\/\/www.dexway.com\/wp-content\/uploads\/2016\/01\/educational-technology.jpg 1075w, https:\/\/www.dexway.com\/wp-content\/uploads\/2016\/01\/educational-technology-300x167.jpg 300w, https:\/\/www.dexway.com\/wp-content\/uploads\/2016\/01\/educational-technology-1024x572.jpg 1024w\" sizes=\"(max-width: 824px) 100vw, 824px\" \/><\/p>\n<p>El e-learning, la ense\u00f1anza apoyada en nuevas tecnolog\u00edas, es considerada como <strong>la forma m\u00e1s avanzada de ense\u00f1ar y aprender idiomas<\/strong>. <a href=\"https:\/\/thejournal.com\/Articles\/2005\/05\/01\/The-Advantages-of-Using-Technology-in-Second-Language-Education.aspx?Page=1\" target=\"_blank\" rel=\"noopener\">Varios estudios<\/a> han demostrado que complementar las clases con refuerzos online es mucho m\u00e1s efectivo que el repaso en libros de texto. La EdTech ha demostrado tambi\u00e9n que mejora las habilidades orales, de resoluci\u00f3n de problemas, o de listening, todas fundamentales a la hora de aprender un nuevo idioma. Por tanto, facilita su ense\u00f1anza en los centros de idiomas, y se traduce en <strong>mejores ratios de aprobados y finalizaci\u00f3n<\/strong>, mayor fidelizaci\u00f3n de los alumnos<\/p>\n<p>&nbsp;<\/p>\n<h2>Tecnolog\u00eda educativa: LMS, blended learning, videoconferencia, gamificaci\u00f3n&#8230;<\/h2>\n<p>Antes de la crisis por coronavirus, una de las razones del <strong>crecimiento de la tecnolog\u00eda educativa<\/strong>\u00a0era precisamente la pasi\u00f3n y el entusiasmo de los educadores. El profesorado de idiomas de todo el mundo ha sido una de las fuerzas tras la innovaci\u00f3n en las aulas. Y eso se refleja en la calidad de la educaci\u00f3n que hoy en d\u00eda se encuentra en las aulas. Apostar por la <strong>eficacia del e-learning<\/strong> es hacerlo por cursos que incluyen herramientas digitales como la <strong>videoconferencia integrada<\/strong> en el curso, <a href=\"http:\/\/www.dexway.com\/es\/laboratorio-de-idiomas\/\">laboratorios de idiomas<\/a>, contenidos interactivos y multimedia, informes de seguimiento, <a href=\"http:\/\/www.dexway.com\/es\/reconocimiento-de-voz\/\">reconocimiento de voz<\/a>, gamificaci\u00f3n o APP para conectarse a los cursos en cualquier lugar, incluso sin conexi\u00f3n a la red.<\/p>\n<p>Gracias a la tecnolog\u00eda educativa y la metodolog\u00eda blended learning se han abierto muchas oportunidades para los estudiantes actuales, Adem\u00e1s, de las sesiones presenciales, pueden continuar con su estudio fuera de clase y de forma mucho m\u00e1s productiva. A esto hay que sumar, que <strong>durante la crisis por COVID-19 ha permitido continuar con las formaciones a distancia<\/strong> cuando era imposible acudir a clase, y que ha establecido unos mecanismos online en las academias que permitir\u00e1n continuar ofreciendo estas modalidades m\u00e1s all\u00e1 de las cuarentenas, para aprovechar <strong>todos los beneficios que aportan y que sus estudiantes estaban demandando<\/strong>.<\/p>\n<p>Si a\u00fan no se ha sumado al cambio o quiere un soluci\u00f3n profesional estable, que de continuidad a su academia online (no servicios gratuitos para el tr\u00e1mite de este tiempo), puede conocer m\u00e1s acerca de nuestros cursos Dexway con plataforma educativa (LMS, <em>learning managament system<\/em>), videoconferencia integrada y herramienta de creaci\u00f3n de cursos (<em>authoring tool<\/em>) para personalizar contenidos y crear cursos desde cero en este blog, y <a href=\"http:\/\/www.dexway.com\/es\/contacto\/\">contactando con nosotros<\/a>.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h3>Tambi\u00e9n le puede interesar:<\/h3>\n<ul>\n<li><a href=\"http:\/\/www.dexway.com\/es\/blended-learning-en-idiomas-beneficios-para-la-educacion\/\">Blended Learning en Idiomas: 4 beneficios para la educaci\u00f3n<\/a><\/li>\n<li><a href=\"http:\/\/www.dexway.com\/es\/razones-colegios-bilingues-estan-pasando-al-blended-learning\/\">9 razones por las que los colegios biling\u00fces se est\u00e1n pasando al Blended Learning<\/a><\/li>\n<li><a href=\"http:\/\/www.dexway.com\/es\/aprendizaje-de-idiomas-para-universidades\/\">Aprendizaje de idiomas para universidades<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>La ense\u00f1anza de idiomas en academias y unidades de idiomas de universidades ha sido tradicionalmente un sector reacio a adoptar tecnolog\u00eda educativa: hasta el momento, era un sector por debajo de la media en transformaci\u00f3n digital. Las causas que lo explican las se\u00f1alamos ampliamente en nuestro libro blanco sobre academias de idiomas y las nuevas [&hellip;]<\/p>\n","protected":false},"author":17,"featured_media":13007,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[97,120],"tags":[],"class_list":["post-17549","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blended-learning-es","category-tecnologias-educativas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tecnolog\u00eda educativa: la forma m\u00e1s avanzada de ense\u00f1ar idiomas<\/title>\n<meta name=\"description\" content=\"La tecnolog\u00eda educativa revoluciona la eficacia en las aulas de idiomas: d\u00e9 continuidad a sus formaciones con clases y contenidos web\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.dexway.com\/es\/tecnologia-educativa-forma-mas-avanzada-ensenar-idiomas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tecnolog\u00eda educativa: la forma m\u00e1s avanzada de ense\u00f1ar idiomas\" \/>\n<meta property=\"og:description\" content=\"La tecnolog\u00eda educativa revoluciona la eficacia en las aulas de idiomas: d\u00e9 continuidad a sus formaciones con clases y contenidos web\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.dexway.com\/es\/tecnologia-educativa-forma-mas-avanzada-ensenar-idiomas\/\" \/>\n<meta property=\"og:site_name\" content=\"Dexway\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dexwayidiomas\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-12T08:38:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-29T10:40:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.dexway.com\/wp-content\/uploads\/2016\/01\/educational-technology.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1075\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dexway Communication\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@mydexway\" \/>\n<meta name=\"twitter:site\" content=\"@mydexway\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dexway Communication\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.dexway.com\\\/es\\\/tecnologia-educativa-forma-mas-avanzada-ensenar-idiomas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.dexway.com\\\/es\\\/tecnologia-educativa-forma-mas-avanzada-ensenar-idiomas\\\/\"},\"author\":{\"name\":\"Dexway Communication\",\"@id\":\"https:\\\/\\\/www.dexway.com\\\/#\\\/schema\\\/person\\\/24dacbb4c32af4ee4577b6c61e4ab06d\"},\"headline\":\"Tecnolog\u00eda educativa: la forma m\u00e1s avanzada de ense\u00f1ar idiomas\",\"datePublished\":\"2020-06-12T08:38:19+00:00\",\"dateModified\":\"2024-07-29T10:40:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.dexway.com\\\/es\\\/tecnologia-educativa-forma-mas-avanzada-ensenar-idiomas\\\/\"},\"wordCount\":609,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.dexway.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.dexway.com\\\/es\\\/tecnologia-educativa-forma-mas-avanzada-ensenar-idiomas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.dexway.com\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/educational-technology.jpg\",\"articleSection\":[\"Blended Learning\",\"Tecnolog\u00edas educativas\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.dexway.com\\\/es\\\/tecnologia-educativa-forma-mas-avanzada-ensenar-idiomas\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.dexway.com\\\/es\\\/tecnologia-educativa-forma-mas-avanzada-ensenar-idiomas\\\/\",\"url\":\"https:\\\/\\\/www.dexway.com\\\/es\\\/tecnologia-educativa-forma-mas-avanzada-ensenar-idiomas\\\/\",\"name\":\"Tecnolog\u00eda educativa: la forma m\u00e1s avanzada de ense\u00f1ar idiomas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.dexway.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.dexway.com\\\/es\\\/tecnologia-educativa-forma-mas-avanzada-ensenar-idiomas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.dexway.com\\\/es\\\/tecnologia-educativa-forma-mas-avanzada-ensenar-idiomas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.dexway.com\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/educational-technology.jpg\",\"datePublished\":\"2020-06-12T08:38:19+00:00\",\"dateModified\":\"2024-07-29T10:40:20+00:00\",\"description\":\"La tecnolog\u00eda educativa revoluciona la eficacia en las aulas de idiomas: d\u00e9 continuidad a sus formaciones con clases y contenidos web\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.dexway.com\\\/es\\\/tecnologia-educativa-forma-mas-avanzada-ensenar-idiomas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.dexway.com\\\/es\\\/tecnologia-educativa-forma-mas-avanzada-ensenar-idiomas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.dexway.com\\\/es\\\/tecnologia-educativa-forma-mas-avanzada-ensenar-idiomas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.dexway.com\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/educational-technology.jpg\",\"contentUrl\":\"https:\\\/\\\/www.dexway.com\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/educational-technology.jpg\",\"width\":1075,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.dexway.com\\\/es\\\/tecnologia-educativa-forma-mas-avanzada-ensenar-idiomas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.dexway.com\\\/es\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tecnolog\u00eda educativa: la forma m\u00e1s avanzada de ense\u00f1ar idiomas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.dexway.com\\\/#website\",\"url\":\"https:\\\/\\\/www.dexway.com\\\/\",\"name\":\"Dexway\",\"description\":\"Innovation in Languages\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.dexway.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.dexway.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.dexway.com\\\/#organization\",\"name\":\"Dexway\",\"url\":\"https:\\\/\\\/www.dexway.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.dexway.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.dexway.com\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/PNG100-innovation-in-languages-Logo-Dexway-RGB.png\",\"contentUrl\":\"https:\\\/\\\/www.dexway.com\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/PNG100-innovation-in-languages-Logo-Dexway-RGB.png\",\"width\":314,\"height\":100,\"caption\":\"Dexway\"},\"image\":{\"@id\":\"https:\\\/\\\/www.dexway.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dexwayidiomas\",\"https:\\\/\\\/x.com\\\/mydexway\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/dexway\\\/\",\"https:\\\/\\\/www.instagram.com\\\/dexway_idiomas\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.dexway.com\\\/#\\\/schema\\\/person\\\/24dacbb4c32af4ee4577b6c61e4ab06d\",\"name\":\"Dexway Communication\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4359ef13f09f65835d2204b77e7fbde0515373b26a06d3652ae957e839ac5859?s=96&d=identicon&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4359ef13f09f65835d2204b77e7fbde0515373b26a06d3652ae957e839ac5859?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4359ef13f09f65835d2204b77e7fbde0515373b26a06d3652ae957e839ac5859?s=96&d=identicon&r=g\",\"caption\":\"Dexway Communication\"},\"sameAs\":[\"http:\\\/\\\/www.dexway.com\\\/wp-admin\\\/\"],\"url\":\"https:\\\/\\\/www.dexway.com\\\/es\\\/author\\\/carmen-dexway\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tecnolog\u00eda educativa: la forma m\u00e1s avanzada de ense\u00f1ar idiomas","description":"La tecnolog\u00eda educativa revoluciona la eficacia en las aulas de idiomas: d\u00e9 continuidad a sus formaciones con clases y contenidos web","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.dexway.com\/es\/tecnologia-educativa-forma-mas-avanzada-ensenar-idiomas\/","og_locale":"es_ES","og_type":"article","og_title":"Tecnolog\u00eda educativa: la forma m\u00e1s avanzada de ense\u00f1ar idiomas","og_description":"La tecnolog\u00eda educativa revoluciona la eficacia en las aulas de idiomas: d\u00e9 continuidad a sus formaciones con clases y contenidos web","og_url":"https:\/\/www.dexway.com\/es\/tecnologia-educativa-forma-mas-avanzada-ensenar-idiomas\/","og_site_name":"Dexway","article_publisher":"https:\/\/www.facebook.com\/dexwayidiomas","article_published_time":"2020-06-12T08:38:19+00:00","article_modified_time":"2024-07-29T10:40:20+00:00","og_image":[{"width":1075,"height":600,"url":"https:\/\/www.dexway.com\/wp-content\/uploads\/2016\/01\/educational-technology.jpg","type":"image\/jpeg"}],"author":"Dexway Communication","twitter_card":"summary_large_image","twitter_creator":"@mydexway","twitter_site":"@mydexway","twitter_misc":{"Escrito por":"Dexway Communication","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.dexway.com\/es\/tecnologia-educativa-forma-mas-avanzada-ensenar-idiomas\/#article","isPartOf":{"@id":"https:\/\/www.dexway.com\/es\/tecnologia-educativa-forma-mas-avanzada-ensenar-idiomas\/"},"author":{"name":"Dexway Communication","@id":"https:\/\/www.dexway.com\/#\/schema\/person\/24dacbb4c32af4ee4577b6c61e4ab06d"},"headline":"Tecnolog\u00eda educativa: la forma m\u00e1s avanzada de ense\u00f1ar idiomas","datePublished":"2020-06-12T08:38:19+00:00","dateModified":"2024-07-29T10:40:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.dexway.com\/es\/tecnologia-educativa-forma-mas-avanzada-ensenar-idiomas\/"},"wordCount":609,"commentCount":0,"publisher":{"@id":"https:\/\/www.dexway.com\/#organization"},"image":{"@id":"https:\/\/www.dexway.com\/es\/tecnologia-educativa-forma-mas-avanzada-ensenar-idiomas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.dexway.com\/wp-content\/uploads\/2016\/01\/educational-technology.jpg","articleSection":["Blended Learning","Tecnolog\u00edas educativas"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.dexway.com\/es\/tecnologia-educativa-forma-mas-avanzada-ensenar-idiomas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.dexway.com\/es\/tecnologia-educativa-forma-mas-avanzada-ensenar-idiomas\/","url":"https:\/\/www.dexway.com\/es\/tecnologia-educativa-forma-mas-avanzada-ensenar-idiomas\/","name":"Tecnolog\u00eda educativa: la forma m\u00e1s avanzada de ense\u00f1ar idiomas","isPartOf":{"@id":"https:\/\/www.dexway.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.dexway.com\/es\/tecnologia-educativa-forma-mas-avanzada-ensenar-idiomas\/#primaryimage"},"image":{"@id":"https:\/\/www.dexway.com\/es\/tecnologia-educativa-forma-mas-avanzada-ensenar-idiomas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.dexway.com\/wp-content\/uploads\/2016\/01\/educational-technology.jpg","datePublished":"2020-06-12T08:38:19+00:00","dateModified":"2024-07-29T10:40:20+00:00","description":"La tecnolog\u00eda educativa revoluciona la eficacia en las aulas de idiomas: d\u00e9 continuidad a sus formaciones con clases y contenidos web","breadcrumb":{"@id":"https:\/\/www.dexway.com\/es\/tecnologia-educativa-forma-mas-avanzada-ensenar-idiomas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.dexway.com\/es\/tecnologia-educativa-forma-mas-avanzada-ensenar-idiomas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.dexway.com\/es\/tecnologia-educativa-forma-mas-avanzada-ensenar-idiomas\/#primaryimage","url":"https:\/\/www.dexway.com\/wp-content\/uploads\/2016\/01\/educational-technology.jpg","contentUrl":"https:\/\/www.dexway.com\/wp-content\/uploads\/2016\/01\/educational-technology.jpg","width":1075,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/www.dexway.com\/es\/tecnologia-educativa-forma-mas-avanzada-ensenar-idiomas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.dexway.com\/es\/home\/"},{"@type":"ListItem","position":2,"name":"Tecnolog\u00eda educativa: la forma m\u00e1s avanzada de ense\u00f1ar idiomas"}]},{"@type":"WebSite","@id":"https:\/\/www.dexway.com\/#website","url":"https:\/\/www.dexway.com\/","name":"Dexway","description":"Innovation in Languages","publisher":{"@id":"https:\/\/www.dexway.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.dexway.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.dexway.com\/#organization","name":"Dexway","url":"https:\/\/www.dexway.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.dexway.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.dexway.com\/wp-content\/uploads\/2018\/09\/PNG100-innovation-in-languages-Logo-Dexway-RGB.png","contentUrl":"https:\/\/www.dexway.com\/wp-content\/uploads\/2018\/09\/PNG100-innovation-in-languages-Logo-Dexway-RGB.png","width":314,"height":100,"caption":"Dexway"},"image":{"@id":"https:\/\/www.dexway.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dexwayidiomas","https:\/\/x.com\/mydexway","https:\/\/www.linkedin.com\/company\/dexway\/","https:\/\/www.instagram.com\/dexway_idiomas\/"]},{"@type":"Person","@id":"https:\/\/www.dexway.com\/#\/schema\/person\/24dacbb4c32af4ee4577b6c61e4ab06d","name":"Dexway Communication","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4359ef13f09f65835d2204b77e7fbde0515373b26a06d3652ae957e839ac5859?s=96&d=identicon&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4359ef13f09f65835d2204b77e7fbde0515373b26a06d3652ae957e839ac5859?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4359ef13f09f65835d2204b77e7fbde0515373b26a06d3652ae957e839ac5859?s=96&d=identicon&r=g","caption":"Dexway Communication"},"sameAs":["http:\/\/www.dexway.com\/wp-admin\/"],"url":"https:\/\/www.dexway.com\/es\/author\/carmen-dexway\/"}]}},"_links":{"self":[{"href":"https:\/\/www.dexway.com\/es\/wp-json\/wp\/v2\/posts\/17549","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dexway.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dexway.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dexway.com\/es\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dexway.com\/es\/wp-json\/wp\/v2\/comments?post=17549"}],"version-history":[{"count":2,"href":"https:\/\/www.dexway.com\/es\/wp-json\/wp\/v2\/posts\/17549\/revisions"}],"predecessor-version":[{"id":28709,"href":"https:\/\/www.dexway.com\/es\/wp-json\/wp\/v2\/posts\/17549\/revisions\/28709"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dexway.com\/es\/wp-json\/wp\/v2\/media\/13007"}],"wp:attachment":[{"href":"https:\/\/www.dexway.com\/es\/wp-json\/wp\/v2\/media?parent=17549"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dexway.com\/es\/wp-json\/wp\/v2\/categories?post=17549"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dexway.com\/es\/wp-json\/wp\/v2\/tags?post=17549"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}