{"id":10947,"date":"2018-06-05T16:00:09","date_gmt":"2018-06-05T14:00:09","guid":{"rendered":"https:\/\/www.dexway.com\/?p=10947"},"modified":"2024-07-23T14:26:51","modified_gmt":"2024-07-23T12:26:51","slug":"cursos-dexway-idiomas-apoyo-completo-libros","status":"publish","type":"post","link":"https:\/\/www.dexway.com\/es\/cursos-dexway-idiomas-apoyo-completo-libros\/","title":{"rendered":"Cursos Dexway Idiomas, el apoyo m\u00e1s completo para sus libros"},"content":{"rendered":"<span class=\"synved-social-container synved-social-container-share\"><a class=\"synved-social-button synved-social-button-share synved-social-size-32 synved-social-resolution-single synved-social-provider-facebook nolightbox\" data-provider=\"facebook\" target=\"_blank\" rel=\"nofollow\" title=\"Share on Facebook\" href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Fwww.dexway.com%2Fes%2Fwp-json%2Fwp%2Fv2%2Fposts%2F10947%2F&amp;t=Cursos%20Dexway%20Idiomas%2C%20el%20apoyo%20m%C3%A1s%20completo%20para%20sus%20libros&amp;s=100&amp;p[url]=https%3A%2F%2Fwww.dexway.com%2Fes%2Fwp-json%2Fwp%2Fv2%2Fposts%2F10947%2F&amp;p[images][0]=https%3A%2F%2Fwww.dexway.com%2Fwp-content%2Fuploads%2F2018%2F06%2Fdexway-classroom-companion.jpg&amp;p[title]=Cursos%20Dexway%20Idiomas%2C%20el%20apoyo%20m%C3%A1s%20completo%20para%20sus%20libros\" style=\"font-size: 0px;width:32px;height:32px;margin:0;margin-bottom:5px;margin-right:5px\"><img loading=\"lazy\" decoding=\"async\" alt=\"Facebook\" title=\"Share on Facebook\" class=\"synved-share-image synved-social-image synved-social-image-share\" width=\"32\" height=\"32\" style=\"display: inline;width:32px;height:32px;margin: 0;padding: 0;border: none;box-shadow: none\" src=\"https:\/\/www.dexway.com\/wp-content\/plugins\/social-media-feather\/synved-social\/addons\/extra-icons\/image\/social\/clearslate\/64x64\/facebook.png\" \/><\/a><a class=\"synved-social-button synved-social-button-share synved-social-size-32 synved-social-resolution-single synved-social-provider-twitter nolightbox\" data-provider=\"twitter\" target=\"_blank\" rel=\"nofollow\" title=\"Share on Twitter\" href=\"https:\/\/twitter.com\/intent\/tweet?url=https%3A%2F%2Fwww.dexway.com%2Fes%2Fwp-json%2Fwp%2Fv2%2Fposts%2F10947%2F&amp;text=Hey%20check%20this%20out\" style=\"font-size: 0px;width:32px;height:32px;margin:0;margin-bottom:5px;margin-right:5px\"><img loading=\"lazy\" decoding=\"async\" alt=\"twitter\" title=\"Share on Twitter\" class=\"synved-share-image synved-social-image synved-social-image-share\" width=\"32\" height=\"32\" style=\"display: inline;width:32px;height:32px;margin: 0;padding: 0;border: none;box-shadow: none\" src=\"https:\/\/www.dexway.com\/wp-content\/plugins\/social-media-feather\/synved-social\/addons\/extra-icons\/image\/social\/clearslate\/64x64\/twitter.png\" \/><\/a><a class=\"synved-social-button synved-social-button-share synved-social-size-32 synved-social-resolution-single synved-social-provider-reddit nolightbox\" data-provider=\"reddit\" target=\"_blank\" rel=\"nofollow\" title=\"Share on Reddit\" href=\"https:\/\/www.reddit.com\/submit?url=https%3A%2F%2Fwww.dexway.com%2Fes%2Fwp-json%2Fwp%2Fv2%2Fposts%2F10947%2F&amp;title=Cursos%20Dexway%20Idiomas%2C%20el%20apoyo%20m%C3%A1s%20completo%20para%20sus%20libros\" style=\"font-size: 0px;width:32px;height:32px;margin:0;margin-bottom:5px;margin-right:5px\"><img loading=\"lazy\" decoding=\"async\" alt=\"reddit\" title=\"Share on Reddit\" class=\"synved-share-image synved-social-image synved-social-image-share\" width=\"32\" height=\"32\" style=\"display: inline;width:32px;height:32px;margin: 0;padding: 0;border: none;box-shadow: none\" src=\"https:\/\/www.dexway.com\/wp-content\/plugins\/social-media-feather\/synved-social\/addons\/extra-icons\/image\/social\/clearslate\/64x64\/reddit.png\" \/><\/a><a class=\"synved-social-button synved-social-button-share synved-social-size-32 synved-social-resolution-single synved-social-provider-pinterest nolightbox\" data-provider=\"pinterest\" target=\"_blank\" rel=\"nofollow\" title=\"Pin it with Pinterest\" href=\"https:\/\/pinterest.com\/pin\/create\/button\/?url=https%3A%2F%2Fwww.dexway.com%2Fes%2Fwp-json%2Fwp%2Fv2%2Fposts%2F10947%2F&amp;media=https%3A%2F%2Fwww.dexway.com%2Fwp-content%2Fuploads%2F2018%2F06%2Fdexway-classroom-companion.jpg&amp;description=Cursos%20Dexway%20Idiomas%2C%20el%20apoyo%20m%C3%A1s%20completo%20para%20sus%20libros\" style=\"font-size: 0px;width:32px;height:32px;margin:0;margin-bottom:5px;margin-right:5px\"><img loading=\"lazy\" decoding=\"async\" alt=\"pinterest\" title=\"Pin it with Pinterest\" class=\"synved-share-image synved-social-image synved-social-image-share\" width=\"32\" height=\"32\" style=\"display: inline;width:32px;height:32px;margin: 0;padding: 0;border: none;box-shadow: none\" src=\"https:\/\/www.dexway.com\/wp-content\/plugins\/social-media-feather\/synved-social\/addons\/extra-icons\/image\/social\/clearslate\/64x64\/pinterest.png\" \/><\/a><a class=\"synved-social-button synved-social-button-share synved-social-size-32 synved-social-resolution-single synved-social-provider-linkedin nolightbox\" data-provider=\"linkedin\" target=\"_blank\" rel=\"nofollow\" title=\"Share on Linkedin\" href=\"https:\/\/www.linkedin.com\/shareArticle?mini=true&amp;url=https%3A%2F%2Fwww.dexway.com%2Fes%2Fwp-json%2Fwp%2Fv2%2Fposts%2F10947%2F&amp;title=Cursos%20Dexway%20Idiomas%2C%20el%20apoyo%20m%C3%A1s%20completo%20para%20sus%20libros\" style=\"font-size: 0px;width:32px;height:32px;margin:0;margin-bottom:5px;margin-right:5px\"><img loading=\"lazy\" decoding=\"async\" alt=\"linkedin\" title=\"Share on Linkedin\" class=\"synved-share-image synved-social-image synved-social-image-share\" width=\"32\" height=\"32\" style=\"display: inline;width:32px;height:32px;margin: 0;padding: 0;border: none;box-shadow: none\" src=\"https:\/\/www.dexway.com\/wp-content\/plugins\/social-media-feather\/synved-social\/addons\/extra-icons\/image\/social\/clearslate\/64x64\/linkedin.png\" \/><\/a><a class=\"synved-social-button synved-social-button-share synved-social-size-32 synved-social-resolution-single synved-social-provider-mail nolightbox\" data-provider=\"mail\" rel=\"nofollow\" title=\"Share by email\" href=\"mailto:?subject=Cursos%20Dexway%20Idiomas%2C%20el%20apoyo%20m%C3%A1s%20completo%20para%20sus%20libros&amp;body=Hey%20check%20this%20out:%20https%3A%2F%2Fwww.dexway.com%2Fes%2Fwp-json%2Fwp%2Fv2%2Fposts%2F10947%2F\" style=\"font-size: 0px;width:32px;height:32px;margin:0;margin-bottom:5px\"><img loading=\"lazy\" decoding=\"async\" alt=\"mail\" title=\"Share by email\" class=\"synved-share-image synved-social-image synved-social-image-share\" width=\"32\" height=\"32\" style=\"display: inline;width:32px;height:32px;margin: 0;padding: 0;border: none;box-shadow: none\" src=\"https:\/\/www.dexway.com\/wp-content\/plugins\/social-media-feather\/synved-social\/addons\/extra-icons\/image\/social\/clearslate\/64x64\/mail.png\" \/><\/a><\/span><div style=\"text-align: justify;\">\n<p>Unas de las preocupaciones m\u00e1s habituales de los centros de idiomas es estar al d\u00eda con las nuevas tecnolog\u00edas. Las nuevas generaciones demandan <strong>contenidos digitales e interactivos en las aulas <\/strong>y los centros se han provisto del hardware necesario, pero el gran problema que se encuentran es el de alimentar con contenidos de calidad las salas de ordenadores y tabletas con las que ya cuentan. En este caso, <strong>Dexway Idiomas<\/strong> se convierte en el apoyo m\u00e1s completo para los libros de texto.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-10948\" src=\"http:\/\/www.dexway.com\/wp-content\/uploads\/2018\/06\/dexway-classroom-companion.jpg\" alt=\"Dexway Idiomas - Dexway Classroom Companion\" width=\"950\" height=\"415\" srcset=\"https:\/\/www.dexway.com\/wp-content\/uploads\/2018\/06\/dexway-classroom-companion.jpg 950w, https:\/\/www.dexway.com\/wp-content\/uploads\/2018\/06\/dexway-classroom-companion-300x131.jpg 300w, https:\/\/www.dexway.com\/wp-content\/uploads\/2018\/06\/dexway-classroom-companion-768x335.jpg 768w, https:\/\/www.dexway.com\/wp-content\/uploads\/2018\/06\/dexway-classroom-companion-610x266.jpg 610w\" sizes=\"(max-width: 950px) 100vw, 950px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Los libros de texto y dem\u00e1s material did\u00e1ctico f\u00edsico ya no son suficientes en unas <strong>aulas tomadas por la tecnolog\u00eda<\/strong>. Es necesario contar con <strong>extensiones digitales<\/strong> capaces de nutrir de contenidos los dispositivos de una manera que complementen a las clases y apoyen la labor de los docentes.<\/p>\n<p>Las <strong>soluciones formativas en Dexway Idiomas<\/strong>\u00a0ofrecen los cursos online complementarios para la ense\u00f1anza en el aula m\u00e1s completos e interactivos del mercado. No se conforme con una simple extensi\u00f3n digital para sus alumnos, ofrezca un curso completo que pueden utilizar dentro y fuera del aula: tanto como para dotar de <strong>recursos multimedia e interactivos<\/strong> a las clases presenciales de sus profesores como para implantar modelos mixtos presencial\/online.<\/p>\n<p>En el aula, <a title=\"Dexway Classroom Companion\" href=\"http:\/\/www.dexway.com\/es\/novedades-en-classroom-companion-ingles-uk-de-a1-a-c1\/\">Dexway Classroom Companion<\/a> es el mejor aliado para las clases presenciales: se adapta al orden y los objetivos del curso planteados por el profesor gracias a una potente <strong>herramienta de autor<\/strong> que permite a los profesores modificar, ampliar o eliminar temario para ajustarlo a su estilo de dar las clases y sus objetivos.<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Soluciones para centros educativos<\/strong><\/h2>\n<p>Dexway ofrece completas extensiones digitales en tres formatos:<\/p>\n<p>&nbsp;<\/p>\n<h3 style=\"font-size: 12pt;\"><strong>#1 CURSO ONLINE A IMAGEN DEL LIBRO<\/strong><\/h3>\n<p>Curso complementario al libro de texto personalizable para adaptarse al orden y temario del libro de texto con el que el profesor trabaja en clase (Dexway Classroom Companion).<\/p>\n<p>&nbsp;<\/p>\n<h3 style=\"font-size: 12pt;\"><strong>#2 CURSO ONLINE A IMAGEN DE LAS CLASES DEL PROFESOR<\/strong><\/h3>\n<p><a title=\"Blended Learning\" href=\"http:\/\/www.dexway.com\/es\/ebook-blended-elearning-idiomas\/\">Curso blended<\/a> m\u00e1s completo, personalizable por el profesor para adaptarlo, no tanto a imagen del libro, sino a su forma de dar las clases y su propia hoja de ruta para el curso (Dexway Classroom Companion).<\/p>\n<p>&nbsp;<\/p>\n<h3 style=\"font-size: 12pt;\"><strong>#3 CURSO ONLINE INDEPENDIENTE<\/strong><\/h3>\n<p>Curso online paralelo para que los alumnos puedan avanzar y practicar en el nivel del curso con un completo curso de idiomas. Aunque los estudiantes trabajan en \u00e9l en paralelo a las clases, el profesor tiene acceso al <a title=\"Dexway incorpora Dexway Analytics\" href=\"http:\/\/www.dexway.com\/es\/dexway-incorpora-analytics-una-funcionalidad-avanzada-de-analisis-y-seguimiento-de-los-alumnos\/\">seguimiento e informes de rendimiento<\/a>, por lo que tambi\u00e9n puede evaluarlo y extraer informaci\u00f3n valiosa (carencias, flaquezas) para sus clases. En este caso, seg\u00fan las necesidades del centro se puede trabajar con la <strong>soluci\u00f3n global de Dexway Idiomas<\/strong>, con acceso a todas las versiones de los cursos, todo el material did\u00e1ctico testado y a la herramienta de edici\u00f3n <a title=\"Dexwat Authoring Tool\" href=\"http:\/\/www.dexway.com\/es\/dexway-authoring-tool\/\">Dexway Authoring Tool<\/a>.<\/p>\n<p>Cualquiera de estas soluciones conserva todas las caracter\u00edsticas que definen a <strong>Dexway<\/strong> como el <strong>m\u00e9todo de idiomas que realmente funciona<\/strong>. Los cursos <strong>Dexway Idiomas<\/strong> basan su metodolog\u00eda en un aprendizaje natural y progresivo de 0 a 100 %, sin lagunas, con <strong>contenidos estructurados<\/strong> que siguen el Marco Com\u00fan Europeo de Referencia para las lenguas (MCER).<\/p>\n<p>Los <strong>contenidos Dexway son interactivos<\/strong> y variados, pensados para mantener la motivaci\u00f3n y el inter\u00e9s de los alumnos durante todo el curso.<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Extensi\u00f3n digital Dexway Idiomas + LMS<\/strong><\/h2>\n<p>Los cursos Dexway cuentan con un <strong>entorno virtual \u00fanico<\/strong> en el que los alumnos interact\u00faan con el curso. Este portal web puede personalizarse para cada centro con su logotipo y sus necesidades espec\u00edficas.<\/p>\n<p>A trav\u00e9s del <strong>LMS de CAE especializado en cursos de idiomas<\/strong> Dexway (Voluxion Pro), los alumnos tienen acceso a las lecciones del curso, as\u00ed como al resto de actividades de Dexway: vocabulario, karaoke, revistas, comunidad de alumnos, grupos de conversaci\u00f3n.<\/p>\n<p><a href=\"http:\/\/www.dexway.com\/es\/contacto\/\">M\u00e1s informaci\u00f3n<\/a> sobre extensiones digitales.<\/p>\n<\/div>\n<p>&nbsp;<\/p>\n<p><strong>Tambi\u00e9n le puede interesar:<\/strong><\/p>\n<ul>\n<li><a title=\"\u00bfPor qu\u00e9 su Academia de idiomas necesita un aula virtual y contenidos digitales de idiomas\" href=\"http:\/\/www.dexway.com\/es\/por-que-academia-idiomas-necesita-aula-virtual-contenidos-digitales-idiomas\/\">\u00bfPor qu\u00e9 su Academia de idiomas necesita un aula virtual y contenidos digitales de idiomas?<\/a><\/li>\n<li><a title=\"5 beneficios de la tecnolog\u00eda educativa para aprender ingl\u00e9s\" href=\"http:\/\/www.dexway.com\/es\/5-beneficios-la-tecnologia-educativa-aprender-ingles\/\">5 beneficios de la tecnolog\u00eda educativa para aprender ingl\u00e9s<\/a><\/li>\n<li><a title=\"Ventajas de establecer un aula virtual de formaci\u00f3n en su academia de idiomas\" href=\"http:\/\/www.dexway.com\/es\/ventajas-aula-virtual-formacion-academia-idiomas\/\">Ventajas de establecer un aula virtual de formaci\u00f3n en su academia de idiomas<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfC\u00f3mo alimentar con contenidos de calidad salas de ordenadores y tabletas? Dexway Idiomas se convierte en el apoyo m\u00e1s completo para libros de texto<\/p>\n","protected":false},"author":17,"featured_media":10948,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[56],"tags":[],"class_list":["post-10947","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cursos-idiomas-online"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cursos Dexway Idiomas, el apoyo m\u00e1s completo para sus libros | Dexway<\/title>\n<meta name=\"description\" content=\"\u00bfC\u00f3mo alimentar con contenidos de calidad salas de ordenadores y tabletas? Dexway Idiomas se convierte en el apoyo m\u00e1s completo para libros de texto\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.dexway.com\/es\/cursos-dexway-idiomas-apoyo-completo-libros\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cursos Dexway Idiomas, el apoyo m\u00e1s completo para sus libros | Dexway\" \/>\n<meta property=\"og:description\" content=\"\u00bfC\u00f3mo alimentar con contenidos de calidad salas de ordenadores y tabletas? Dexway Idiomas se convierte en el apoyo m\u00e1s completo para libros de texto\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.dexway.com\/es\/cursos-dexway-idiomas-apoyo-completo-libros\/\" \/>\n<meta property=\"og:site_name\" content=\"Dexway\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dexwayidiomas\" \/>\n<meta property=\"article:published_time\" content=\"2018-06-05T14:00:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-23T12:26:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.dexway.com\/wp-content\/uploads\/2018\/06\/dexway-classroom-companion.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"950\" \/>\n\t<meta property=\"og:image:height\" content=\"415\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dexway Communication\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@mydexway\" \/>\n<meta name=\"twitter:site\" content=\"@mydexway\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dexway Communication\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.dexway.com\\\/es\\\/cursos-dexway-idiomas-apoyo-completo-libros\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.dexway.com\\\/es\\\/cursos-dexway-idiomas-apoyo-completo-libros\\\/\"},\"author\":{\"name\":\"Dexway Communication\",\"@id\":\"https:\\\/\\\/www.dexway.com\\\/#\\\/schema\\\/person\\\/24dacbb4c32af4ee4577b6c61e4ab06d\"},\"headline\":\"Cursos Dexway Idiomas, el apoyo m\u00e1s completo para sus libros\",\"datePublished\":\"2018-06-05T14:00:09+00:00\",\"dateModified\":\"2024-07-23T12:26:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.dexway.com\\\/es\\\/cursos-dexway-idiomas-apoyo-completo-libros\\\/\"},\"wordCount\":699,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.dexway.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.dexway.com\\\/es\\\/cursos-dexway-idiomas-apoyo-completo-libros\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.dexway.com\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/dexway-classroom-companion.jpg\",\"articleSection\":[\"Idiomas online\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.dexway.com\\\/es\\\/cursos-dexway-idiomas-apoyo-completo-libros\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.dexway.com\\\/es\\\/cursos-dexway-idiomas-apoyo-completo-libros\\\/\",\"url\":\"https:\\\/\\\/www.dexway.com\\\/es\\\/cursos-dexway-idiomas-apoyo-completo-libros\\\/\",\"name\":\"Cursos Dexway Idiomas, el apoyo m\u00e1s completo para sus libros | Dexway\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.dexway.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.dexway.com\\\/es\\\/cursos-dexway-idiomas-apoyo-completo-libros\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.dexway.com\\\/es\\\/cursos-dexway-idiomas-apoyo-completo-libros\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.dexway.com\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/dexway-classroom-companion.jpg\",\"datePublished\":\"2018-06-05T14:00:09+00:00\",\"dateModified\":\"2024-07-23T12:26:51+00:00\",\"description\":\"\u00bfC\u00f3mo alimentar con contenidos de calidad salas de ordenadores y tabletas? Dexway Idiomas se convierte en el apoyo m\u00e1s completo para libros de texto\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.dexway.com\\\/es\\\/cursos-dexway-idiomas-apoyo-completo-libros\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.dexway.com\\\/es\\\/cursos-dexway-idiomas-apoyo-completo-libros\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.dexway.com\\\/es\\\/cursos-dexway-idiomas-apoyo-completo-libros\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.dexway.com\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/dexway-classroom-companion.jpg\",\"contentUrl\":\"https:\\\/\\\/www.dexway.com\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/dexway-classroom-companion.jpg\",\"width\":950,\"height\":415,\"caption\":\"Dexway Classroom Companion\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.dexway.com\\\/es\\\/cursos-dexway-idiomas-apoyo-completo-libros\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.dexway.com\\\/es\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cursos Dexway Idiomas, el apoyo m\u00e1s completo para sus libros\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.dexway.com\\\/#website\",\"url\":\"https:\\\/\\\/www.dexway.com\\\/\",\"name\":\"Dexway\",\"description\":\"Innovation in Languages\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.dexway.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.dexway.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.dexway.com\\\/#organization\",\"name\":\"Dexway\",\"url\":\"https:\\\/\\\/www.dexway.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.dexway.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.dexway.com\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/PNG100-innovation-in-languages-Logo-Dexway-RGB.png\",\"contentUrl\":\"https:\\\/\\\/www.dexway.com\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/PNG100-innovation-in-languages-Logo-Dexway-RGB.png\",\"width\":314,\"height\":100,\"caption\":\"Dexway\"},\"image\":{\"@id\":\"https:\\\/\\\/www.dexway.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dexwayidiomas\",\"https:\\\/\\\/x.com\\\/mydexway\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/dexway\\\/\",\"https:\\\/\\\/www.instagram.com\\\/dexway_idiomas\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.dexway.com\\\/#\\\/schema\\\/person\\\/24dacbb4c32af4ee4577b6c61e4ab06d\",\"name\":\"Dexway Communication\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4359ef13f09f65835d2204b77e7fbde0515373b26a06d3652ae957e839ac5859?s=96&d=identicon&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4359ef13f09f65835d2204b77e7fbde0515373b26a06d3652ae957e839ac5859?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4359ef13f09f65835d2204b77e7fbde0515373b26a06d3652ae957e839ac5859?s=96&d=identicon&r=g\",\"caption\":\"Dexway Communication\"},\"sameAs\":[\"http:\\\/\\\/www.dexway.com\\\/wp-admin\\\/\"],\"url\":\"https:\\\/\\\/www.dexway.com\\\/es\\\/author\\\/carmen-dexway\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cursos Dexway Idiomas, el apoyo m\u00e1s completo para sus libros | Dexway","description":"\u00bfC\u00f3mo alimentar con contenidos de calidad salas de ordenadores y tabletas? Dexway Idiomas se convierte en el apoyo m\u00e1s completo para libros de texto","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.dexway.com\/es\/cursos-dexway-idiomas-apoyo-completo-libros\/","og_locale":"es_ES","og_type":"article","og_title":"Cursos Dexway Idiomas, el apoyo m\u00e1s completo para sus libros | Dexway","og_description":"\u00bfC\u00f3mo alimentar con contenidos de calidad salas de ordenadores y tabletas? Dexway Idiomas se convierte en el apoyo m\u00e1s completo para libros de texto","og_url":"https:\/\/www.dexway.com\/es\/cursos-dexway-idiomas-apoyo-completo-libros\/","og_site_name":"Dexway","article_publisher":"https:\/\/www.facebook.com\/dexwayidiomas","article_published_time":"2018-06-05T14:00:09+00:00","article_modified_time":"2024-07-23T12:26:51+00:00","og_image":[{"width":950,"height":415,"url":"https:\/\/www.dexway.com\/wp-content\/uploads\/2018\/06\/dexway-classroom-companion.jpg","type":"image\/jpeg"}],"author":"Dexway Communication","twitter_card":"summary_large_image","twitter_creator":"@mydexway","twitter_site":"@mydexway","twitter_misc":{"Escrito por":"Dexway Communication","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.dexway.com\/es\/cursos-dexway-idiomas-apoyo-completo-libros\/#article","isPartOf":{"@id":"https:\/\/www.dexway.com\/es\/cursos-dexway-idiomas-apoyo-completo-libros\/"},"author":{"name":"Dexway Communication","@id":"https:\/\/www.dexway.com\/#\/schema\/person\/24dacbb4c32af4ee4577b6c61e4ab06d"},"headline":"Cursos Dexway Idiomas, el apoyo m\u00e1s completo para sus libros","datePublished":"2018-06-05T14:00:09+00:00","dateModified":"2024-07-23T12:26:51+00:00","mainEntityOfPage":{"@id":"https:\/\/www.dexway.com\/es\/cursos-dexway-idiomas-apoyo-completo-libros\/"},"wordCount":699,"commentCount":0,"publisher":{"@id":"https:\/\/www.dexway.com\/#organization"},"image":{"@id":"https:\/\/www.dexway.com\/es\/cursos-dexway-idiomas-apoyo-completo-libros\/#primaryimage"},"thumbnailUrl":"https:\/\/www.dexway.com\/wp-content\/uploads\/2018\/06\/dexway-classroom-companion.jpg","articleSection":["Idiomas online"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.dexway.com\/es\/cursos-dexway-idiomas-apoyo-completo-libros\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.dexway.com\/es\/cursos-dexway-idiomas-apoyo-completo-libros\/","url":"https:\/\/www.dexway.com\/es\/cursos-dexway-idiomas-apoyo-completo-libros\/","name":"Cursos Dexway Idiomas, el apoyo m\u00e1s completo para sus libros | Dexway","isPartOf":{"@id":"https:\/\/www.dexway.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.dexway.com\/es\/cursos-dexway-idiomas-apoyo-completo-libros\/#primaryimage"},"image":{"@id":"https:\/\/www.dexway.com\/es\/cursos-dexway-idiomas-apoyo-completo-libros\/#primaryimage"},"thumbnailUrl":"https:\/\/www.dexway.com\/wp-content\/uploads\/2018\/06\/dexway-classroom-companion.jpg","datePublished":"2018-06-05T14:00:09+00:00","dateModified":"2024-07-23T12:26:51+00:00","description":"\u00bfC\u00f3mo alimentar con contenidos de calidad salas de ordenadores y tabletas? Dexway Idiomas se convierte en el apoyo m\u00e1s completo para libros de texto","breadcrumb":{"@id":"https:\/\/www.dexway.com\/es\/cursos-dexway-idiomas-apoyo-completo-libros\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.dexway.com\/es\/cursos-dexway-idiomas-apoyo-completo-libros\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.dexway.com\/es\/cursos-dexway-idiomas-apoyo-completo-libros\/#primaryimage","url":"https:\/\/www.dexway.com\/wp-content\/uploads\/2018\/06\/dexway-classroom-companion.jpg","contentUrl":"https:\/\/www.dexway.com\/wp-content\/uploads\/2018\/06\/dexway-classroom-companion.jpg","width":950,"height":415,"caption":"Dexway Classroom Companion"},{"@type":"BreadcrumbList","@id":"https:\/\/www.dexway.com\/es\/cursos-dexway-idiomas-apoyo-completo-libros\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.dexway.com\/es\/home\/"},{"@type":"ListItem","position":2,"name":"Cursos Dexway Idiomas, el apoyo m\u00e1s completo para sus libros"}]},{"@type":"WebSite","@id":"https:\/\/www.dexway.com\/#website","url":"https:\/\/www.dexway.com\/","name":"Dexway","description":"Innovation in Languages","publisher":{"@id":"https:\/\/www.dexway.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.dexway.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.dexway.com\/#organization","name":"Dexway","url":"https:\/\/www.dexway.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.dexway.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.dexway.com\/wp-content\/uploads\/2018\/09\/PNG100-innovation-in-languages-Logo-Dexway-RGB.png","contentUrl":"https:\/\/www.dexway.com\/wp-content\/uploads\/2018\/09\/PNG100-innovation-in-languages-Logo-Dexway-RGB.png","width":314,"height":100,"caption":"Dexway"},"image":{"@id":"https:\/\/www.dexway.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dexwayidiomas","https:\/\/x.com\/mydexway","https:\/\/www.linkedin.com\/company\/dexway\/","https:\/\/www.instagram.com\/dexway_idiomas\/"]},{"@type":"Person","@id":"https:\/\/www.dexway.com\/#\/schema\/person\/24dacbb4c32af4ee4577b6c61e4ab06d","name":"Dexway Communication","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4359ef13f09f65835d2204b77e7fbde0515373b26a06d3652ae957e839ac5859?s=96&d=identicon&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4359ef13f09f65835d2204b77e7fbde0515373b26a06d3652ae957e839ac5859?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4359ef13f09f65835d2204b77e7fbde0515373b26a06d3652ae957e839ac5859?s=96&d=identicon&r=g","caption":"Dexway Communication"},"sameAs":["http:\/\/www.dexway.com\/wp-admin\/"],"url":"https:\/\/www.dexway.com\/es\/author\/carmen-dexway\/"}]}},"_links":{"self":[{"href":"https:\/\/www.dexway.com\/es\/wp-json\/wp\/v2\/posts\/10947","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dexway.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dexway.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dexway.com\/es\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dexway.com\/es\/wp-json\/wp\/v2\/comments?post=10947"}],"version-history":[{"count":3,"href":"https:\/\/www.dexway.com\/es\/wp-json\/wp\/v2\/posts\/10947\/revisions"}],"predecessor-version":[{"id":28653,"href":"https:\/\/www.dexway.com\/es\/wp-json\/wp\/v2\/posts\/10947\/revisions\/28653"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dexway.com\/es\/wp-json\/wp\/v2\/media\/10948"}],"wp:attachment":[{"href":"https:\/\/www.dexway.com\/es\/wp-json\/wp\/v2\/media?parent=10947"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dexway.com\/es\/wp-json\/wp\/v2\/categories?post=10947"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dexway.com\/es\/wp-json\/wp\/v2\/tags?post=10947"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}